{"id":285,"date":"2017-09-09T12:57:11","date_gmt":"2017-09-09T12:57:11","guid":{"rendered":"http:\/\/gestion.reseauxlibres.be\/wordpress\/?p=285"},"modified":"2017-09-02T13:20:24","modified_gmt":"2017-09-02T13:20:24","slug":"les-neurosciences-au-coeur-de-la-classe","status":"publish","type":"post","link":"https:\/\/gestion.reseauxlibres.be\/wordpress\/les-neurosciences-au-coeur-de-la-classe\/","title":{"rendered":"Les neurosciences au c\u0153ur de la classe"},"content":{"rendered":"<p>Sur ce <a href=\"https:\/\/clio-cr.clionautes.org\" target=\"_blank\">site<\/a>, appel\u00e9 &#8220;La Clioth\u00e8que&#8221;, vous trouverez des comptes-rendus d&#8217;ouvrages essentiellement en lien avec l&#8217;histoire et la g\u00e9ographie, mais aussi parfois avec\u00a0la p\u00e9dagogie, \u00e0 explorer pour y glaner des pistes, des id\u00e9es en lien avec le m\u00e9tier d&#8217;enseignant et les mati\u00e8res pr\u00e9cit\u00e9es.<\/p>\n<p>J&#8217;ai rep\u00e9r\u00e9\u00a0un <a href=\"https:\/\/clio-cr.clionautes.org\/les-neurosciences-de-l-education-de-la-theorie-a-la-pratique-en-classe.html\" target=\"_blank\">conseil de lecture<\/a>: &#8220;Les neurosciences au c\u0153ur de la classe&#8221;, sous la direction de Pascale Toscani, Chronique Sociale, 2014.<\/p>\n<p>Voici un extrait de la pr\u00e9sentation de l&#8217;ouvrage, r\u00e9dig\u00e9e par Jean-Pierre Costille, pour les Clionautes.<\/p>\n<blockquote><p><strong>&#8220;<em>Vers une p\u00e9dagogie de l\u2019attention &#8211;\u00a0<\/em><\/strong><\/p>\n<p><em>Cette partie pr\u00e9cise d\u2019abord les trois formes d\u2019attention dont chacun est dot\u00e9 et d\u00e9cline quelques pistes concr\u00e8tes pour la classe. Les auteurs pointent les limites attentionnelles en rappelant par exemple l\u2019exp\u00e9rience de Chabris et Simmons autrement baptis\u00e9e exp\u00e9rience du \u00ab\u00a0gorille invisible\u00a0\u00bb. Il faut aussi tenir compte du fait que, malgr\u00e9 une activit\u00e9 parfois fr\u00e9n\u00e9tique, nous ne sommes pas multit\u00e2ches. Il est fondamental d\u2019en tenir compte quand on fait classe. Les auteurs proposent un tr\u00e8s utile tableau sur les \u00ab\u00a0instructions qui favorisent l\u2019attention\u00a0\u00bb. Ils plaident aussi pour que ces informations soient communiqu\u00e9s aux \u00e9l\u00e8ves, par exemple durant les heures d\u2019accompagnement personnalis\u00e9.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>La m\u00e9moire, les m\u00e9moires et l\u2019apprentissage &#8211;\u00a0<\/strong><\/em><\/p>\n<p><em>Ce chapitre permet de distinguer les cinq grands syst\u00e8mes de m\u00e9moire en insistant aussi sur le r\u00f4le et les limites de la m\u00e9moire de travail. Le chapitre aborde en quelques lignes tr\u00e8s claires ces cinq formes de la m\u00e9moire. L\u2019encodage, la consolidation et le rappel sont \u00e9galement trois aspects essentiels dont il faut tenir compte. Au niveau de la r\u00e9activation, il faut laisser du temps aux \u00e9l\u00e8ves au d\u00e9but, pendant, ou \u00e0 la fin des cours en pr\u00e9sence du professeur.<\/em>&#8220;<\/p><\/blockquote>\n<p>Il s&#8217;agit \u00e0 mon sens d&#8217;un excellent compl\u00e9ment \u00e0 la p\u00e9dagogie des gestes mentaux et dans le cas pr\u00e9sent, aux gestes d&#8217;attention et de m\u00e9morisation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur ce site, appel\u00e9 &#8220;La Clioth\u00e8que&#8221;, vous trouverez des comptes-rendus d&#8217;ouvrages essentiellement en lien avec l&#8217;histoire et la g\u00e9ographie, mais aussi parfois avec\u00a0la p\u00e9dagogie, \u00e0 explorer pour y glaner des pistes, des id\u00e9es en lien avec le m\u00e9tier d&#8217;enseignant et les mati\u00e8res pr\u00e9cit\u00e9es. J&#8217;ai rep\u00e9r\u00e9\u00a0un conseil de lecture: &#8220;Les neurosciences au c\u0153ur de la classe&#8221;, sous la direction de Pascale<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[55,41,57,58,56,39,38,51],"tags":[],"class_list":["post-285","post","type-post","status-publish","format-standard","hentry","category-bibliographie","category-en-ligne","category-geographie","category-histoire","category-lattention-les-ressources-en-gestion-mentale","category-la-memorisation","category-les-gestes-mentaux","category-neurosciences-et-gestion-mentale"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/posts\/285"}],"collection":[{"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/comments?post=285"}],"version-history":[{"count":2,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/posts\/285\/revisions"}],"predecessor-version":[{"id":287,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/posts\/285\/revisions\/287"}],"wp:attachment":[{"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/media?parent=285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/categories?post=285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestion.reseauxlibres.be\/wordpress\/wp-json\/wp\/v2\/tags?post=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}